{"id":36548,"date":"2025-04-28T09:37:54","date_gmt":"2025-04-28T16:37:54","guid":{"rendered":"https:\/\/teach.udemy.com\/?page_id=36548"},"modified":"2025-12-22T04:16:13","modified_gmt":"2025-12-22T12:16:13","slug":"frequently-asked-questions-role-play","status":"publish","type":"page","link":"https:\/\/teach.udemy.com\/it\/frequently-asked-questions-role-play\/","title":{"rendered":"Domande frequenti: Gioco di ruolo"},"content":{"rendered":"<h5>Feedback? Condividi il tuo feedback o come utilizzi la funzione Gioco di ruolo nei tuoi corsi con altri insegnanti nella nostra <a href=\"https:\/\/community.udemy.com\/discussion\/160034\/megathread-say-hello-to-role-play\/p1?new=1\">community degli insegnanti<\/a>.  Non hai un account? Registrarsi \u00e8 facile.<\/h5>\n<p>\u00a0<\/p>\n<ul>\n<li><a href=\"#section-1\"><span style=\"font-weight: 400\">Creare giochi di ruolo<\/span><\/a><\/li>\n<li><a href=\"#section-2\"><span style=\"font-weight: 400\">Aggiungere Gioco di ruolo ai tuoi corsi<\/span><\/a><\/li>\n<li><a href=\"#section-3\"><span style=\"font-weight: 400\">Gestione dei contenuti<\/span><\/a><\/li>\n<li><a href=\"#section-4\"><span style=\"font-weight: 400\">La tecnologia dietro Gioco di ruolo<\/span><\/a><\/li>\n<li><span style=\"font-weight: 400\"><a href=\"#section-5\">Monetizzazione<\/a><br \/>\n<\/span><\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<h2 id=\"section-1\"><b>Creare giochi di ruolo<\/b><\/h2>\n<h3><b>1. Come si pu\u00f2, da insegnante, creare un gioco di ruolo?<\/b><\/h3>\n<p>Come creare un gioco di ruolo:<\/p>\n<ol>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Inserisci un gioco di ruolo nel punto giusto<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><span style=\"font-weight: 400\">Posiziona il gioco di ruolo nella sezione in cui si integra alla perfezione con le competenze e lezioni del corso. Per esempio:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Dopo una lezione sulla comunicazione sul posto di lavoro, aggiungi un gioco di ruolo per far fare pratica ai tuoi studenti su come gestire un conflitto.<\/span><\/li>\n<\/ul>\n<\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Crea un titolo accattivante<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><span style=\"font-weight: 400\">Utilizza un titolo chiaro e accattivante che rifletta le competenze che gli studenti metteranno in pratica.<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><span style=\"font-weight: 400\">Esempi:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">&#8220;Come risolvere un conflitto nel team&#8221;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">&#8220;Negoziare un accordo commerciale con un cliente&#8221;<\/span><\/li>\n<\/ul>\n<\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Pianifica lo scenario<\/span>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Crea una situazione realistica: descrivi chiaramente il ruolo dello studente (ad esempio, il team leader) e la sfida che dovr\u00e0 affrontare.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Fornisci un contesto: aggiungi dettagli rilevanti in modo che gli studenti possano prendere decisioni basate sulla conoscenza della situazione.<\/span><\/li>\n<\/ul>\n<\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Personalizza il personaggio IA<\/span>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Scegli il nome, l&#8217;avatar e la personalit\u00e0 del personaggio IA.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Crea il background e la prima battuta del personaggio per impostare il tono dell&#8217;interazione.<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><span style=\"font-weight: 400\">Esempio:<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Personaggio: Jordan, un membro del team che fatica a rispettare le scadenze.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Prima battuta: &#8220;Grazie per essere qui. Vorrei spiegarvi il motivo dietro i miei ritardi.&#8221;<\/span><\/li>\n<\/ul>\n<\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Imposta obiettivi e dettagli<\/span>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Crea un titolo per la riunione (ad esempio, &#8220;Riunione per discutere sulle prestazioni&#8221;).<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Stabilisci obiettivi chiari e misurabili per l&#8217;interazione (ad esempio, &#8220;Fare due domande chiarificatrici&#8221;).<\/span><\/li>\n<\/ul>\n<\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Punta a coinvolgere gli studenti<\/span>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Assicurati che lo scenario e il personaggio consentano agli studenti di mettere in pratica attivamente le competenze in sfide realistiche.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Allinea il gioco di ruolo ad attivit\u00e0 reali per aumentarne il valore pratico.<\/span><\/li>\n<\/ul>\n<\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Prima della pubblicazione, ti preghiamo di rivedere il gioco di ruolo per assicurarti che sia conforme alla sezione &#8220;Obblighi dell&#8217;insegnante&#8221; di Udemy. <\/span><a href=\"https:\/\/support.udemy.com\/hc\/articles\/25180159300631-Instructor-Generative-AI-Policy?\"><span style=\"font-weight: 400\">Politica sulla GenAI<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/li>\n<\/ol>\n<ol><!-- Content --><\/ol>\n<p>Per istruzioni pi\u00f9 approfondite, consulta la nostra <a href=\"https:\/\/teach.udemy.com\/it\/how-to-create-role-plays-for-your-course\/\">Guida<\/a><\/p>\n<p>\u00a0<\/p>\n<h3><b>2. Quali input sono obbligatori\/facoltativi durante la creazione del gioco di ruolo?<\/b><\/h3>\n<h4>Input obbligatori per la creazione di scenari con un gioco di ruolo:<\/h4>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Titolo del gioco di ruolo (che sar\u00e0 visualizzato nel contenuto del corso)<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Scenario<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Ruolo dello studente<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Immagine e voce del personaggio IA, ruolo, personalit\u00e0 e background, prima battuta del personaggio IA<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Titolo della riunione,\u00a0 durata della riunione<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Raggiungimento degli obiettivi (almeno un obiettivo \u00e8 obbligatorio, ma \u00e8 possibile raggiungere fino a 5 obiettivi a discrezione dell&#8217;insegnante)<\/span><\/li>\n<\/ul>\n<ul><!-- Content --><\/ul>\n<p>\u00a0<\/p>\n<h3><b>3. Quali input vengono utilizzati dal LLM per strutturare le conversazioni del gioco di ruolo?<\/b><\/h3>\n<p>Il LLM utilizza i seguenti input per strutturare le conversazioni del gioco di ruolo:<\/p>\n<ol><!-- Content --><\/ol>\n<ol>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Titolo del gioco di ruolo: un chiaro riassunto dell&#8217;obiettivo dello scenario e delle competenze con cui fare pratica.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Scenario: il contesto, il ruolo dello studente e le sfide all&#8217;interno di uno scenario realistico.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Ruolo dello studente<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Raggiungere gli obiettivi: obiettivi osservabili e misurabili che gli studenti devono raggiungere (ad esempio, fornire un feedback costruttivo).<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Nome del personaggio IA<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Ruolo e background del personaggio IA: lavoro del personaggio, personalit\u00e0, motivazioni, ecc.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Prima battuta del personaggio IA: la prima battuta del personaggio IA per stabilire chiaramente la situazione.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Durata: tempo assegnato per completare la conversazione.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400\">Questi input aiutano a rendere l&#8217;interazione del gioco di ruolo realistica, coinvolgente e allineata con gli obiettivi di apprendimento.<\/span> <b><\/b><\/p>\n<p>\u00a0<\/p>\n<h3><b>4.  Gli studenti possono accedere ai giochi di ruolo non appena li pubblico? Quando gli studenti possono accedere al gioco di ruolo?<\/b><\/h3>\n<p><span style=\"font-weight: 400\">Gli studenti possono accedere ai giochi di ruolo creati nelle seguenti lingue immediatamente dopo la pubblicazione del gioco di ruolo:<\/span><\/p>\n<ul>\n<li data-list-item-id=\"e29c48510bc6bd13c748025b4f931b8fe\">Arabo<\/li>\n<li data-list-item-id=\"e0944b260d441265781282fbbb187857c\">Inglese<\/li>\n<li data-list-item-id=\"e8245533631afe29b3a0598ac78aa767a\">danese<\/li>\n<li data-list-item-id=\"e775a5524ca5ff5bed6846c635c50cf56\">Olandese<\/li>\n<li data-list-item-id=\"e4f3e052cf46c2a9878f0fb0b7750e534\">Francese<\/li>\n<li data-list-item-id=\"e9e7d7c5a2f82ec1bd29b3ea4b88ce251\">Tedesco<\/li>\n<li data-list-item-id=\"eb7daeeb21e73711012060ff33692c2aa\">Giapponese<\/li>\n<li data-list-item-id=\"ee41e44c52d45f34191a2cf157b3ae776\">Coreano<\/li>\n<li data-list-item-id=\"e7d73ffe3af6027647bde60433c42f452\">Norvegese<\/li>\n<li data-list-item-id=\"ef9baa05e6d2af3c1b485e0cbab962297\">Polacco<\/li>\n<li data-list-item-id=\"e00123d7e41231153b979901876c751b6\">Portoghese<\/li>\n<li data-list-item-id=\"ed605266c560923209a72a625dccd738b\">Russo<\/li>\n<li class=\"ck-list-marker-color\" data-list-item-id=\"e8953097a44c2cb9bbd8b85bebde33cc3\">Spagnolo<\/li>\n<li data-list-item-id=\"e24b43894b73d5af8ec2832d7b1b9c3a4\">svedese<\/li>\n<li data-list-item-id=\"e1ed5c2fffc9762b75cac749f333ca8b1\">Turco<\/li>\n<li data-list-item-id=\"e958a887d6b2cafb13e13ec394c13b5a5\">Spagnolo<\/li>\n<li data-list-item-id=\"ec9387509d4170b738120168c4713d5cc\">Vietnamita<\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">In futuro potranno essere disponibili altre lingue. Per i dettagli pi\u00f9 recenti, visita il <a href=\"https:\/\/support.udemy.com\/hc\/it\/articles\/34467211373591-Udemy-s-AI-Tools-Instructor-Supported-Languages?\">Centro assistenza<\/a><\/span><\/p>\n<h3><b>5. Sar\u00e0 imposto un limite al numero di giochi di ruolo per corso?<\/b><\/h3>\n<p>No, non ci saranno limiti al numero di giochi di ruolo per corso. Tuttavia, incoraggiamo gli insegnanti a inserire il gioco di ruolo dove ha pi\u00f9 senso per gli studenti esercitarsi e raggiungere i loro obiettivi di apprendimento. Per maggiori informazioni, consultare la nostra <a href=\"https:\/\/teach.udemy.com\/it\/how-to-create-role-plays-for-your-course\/\">guida alla creazione di un gioco di ruolo<\/a><\/p>\n<p>\u00a0<\/p>\n<h3><b>6. \u00c8 possibile caricare un&#8217;immagine per il personaggio IA?<\/b><\/h3>\n<p>No, attualmente non \u00e8 possibile caricare un&#8217;immagine. Attualmente i personaggi IA sono predefiniti come opzioni di immagine e di coppia nella biblioteca dei giochi di ruolo, da scegliere quando si creano i giochi di ruolo.<\/p>\n<p>\u00a0<\/p>\n<h3><b>7. Chi fornisce la voce e l&#8217;aspetto dei personaggi IA<\/b><\/h3>\n<p>Udemy utilizza ElevenLabs per le opzioni vocali e Lummi.ai per le opzioni di immagine dei personaggi IA.<\/p>\n<p>\u00a0<\/p>\n<h2 id=\"section-2\"><b>Aggiungere Gioco di ruolo ai tuoi corsi<\/b><\/h2>\n<h3><b>8. I giochi di ruolo si troveranno all&#8217;interno dei corsi o saranno in una scheda separata (come AI Assistant)?<\/b><\/h3>\n<p>I giochi di ruolo saranno integrati direttamente nei corsi, anzich\u00e9 esistere come scheda separata come AI Assistant. Sono progettati per allinearsi ai contenuti del corso e migliorare l&#8217;esperienza di apprendimento all&#8217;interno della struttura del corso.<\/p>\n<p>\u00a0<\/p>\n<h3><b>9. Ci saranno limitazioni per quanto riguarda gli studenti che possono accedere ai giochi di ruolo?<\/b><\/h3>\n<p>Per gli studenti di Udemy Business, le organizzazioni UB devono avere abilitato Gioco di ruolo per consentire ai loro studenti di accedervi. Per i partecipanti al marketplace, se il corso prevede un gioco di ruolo, i partecipanti potranno accedervi.<\/p>\n<p>\u00a0<\/p>\n<h3><b>10. Ci sar\u00e0 un supporto web mobile per gli insegnanti per creare un gioco di ruolo?<\/b><\/h3>\n<p>Per il momento, la creazione di giochi di ruolo sar\u00e0 supportata solo su desktop e computer portatili.<\/p>\n<p>\u00a0<\/p>\n<h3><b>11. In quali lingue sono disponibili i giochi di ruolo?<\/b><\/h3>\n<p>Al momento, la funzione Gioco di ruolo per gli insegnanti \u00e8 disponibile nelle seguenti lingue:<\/p>\n<ul>\n<li data-list-item-id=\"e29c48510bc6bd13c748025b4f931b8fe\">Arabo<\/li>\n<li data-list-item-id=\"e0944b260d441265781282fbbb187857c\">Inglese<\/li>\n<li data-list-item-id=\"e8245533631afe29b3a0598ac78aa767a\">danese<\/li>\n<li data-list-item-id=\"e775a5524ca5ff5bed6846c635c50cf56\">Olandese<\/li>\n<li data-list-item-id=\"e4f3e052cf46c2a9878f0fb0b7750e534\">Francese<\/li>\n<li data-list-item-id=\"e9e7d7c5a2f82ec1bd29b3ea4b88ce251\">Tedesco<\/li>\n<li data-list-item-id=\"eb7daeeb21e73711012060ff33692c2aa\">Giapponese<\/li>\n<li data-list-item-id=\"ee41e44c52d45f34191a2cf157b3ae776\">Coreano<\/li>\n<li data-list-item-id=\"e7d73ffe3af6027647bde60433c42f452\">Norvegese<\/li>\n<li data-list-item-id=\"ef9baa05e6d2af3c1b485e0cbab962297\">Polacco<\/li>\n<li data-list-item-id=\"e00123d7e41231153b979901876c751b6\">Portoghese<\/li>\n<li data-list-item-id=\"ed605266c560923209a72a625dccd738b\">Russo<\/li>\n<li class=\"ck-list-marker-color\" data-list-item-id=\"e8953097a44c2cb9bbd8b85bebde33cc3\">Spagnolo<\/li>\n<li data-list-item-id=\"e24b43894b73d5af8ec2832d7b1b9c3a4\">svedese<\/li>\n<li data-list-item-id=\"e1ed5c2fffc9762b75cac749f333ca8b1\">Turco<\/li>\n<li data-list-item-id=\"e958a887d6b2cafb13e13ec394c13b5a5\">Spagnolo<\/li>\n<li data-list-item-id=\"ec9387509d4170b738120168c4713d5cc\">Vietnamita<\/li>\n<\/ul>\n<p>\u00c8 previsto un ampliamento progressivo della disponibilit\u00e0 delle lingue. Per i dettagli pi\u00f9 recenti, visita il <a href=\"https:\/\/support.udemy.com\/hc\/it\/articles\/34467211373591-Udemy-s-AI-Tools-Instructor-Supported-Languages?\">Centro assistenza<\/a>.<\/p>\n<p><b>12. I corsi che contengono giochi di ruolo avranno un tag che li contraddistingue in quanto tali?<\/b><\/p>\n<p>S\u00ec, la pagina di destinazione del corso e le schede del corso metteranno in evidenza la presenza di eventuali giochi di ruolo aggiunti ai corsi.<\/p>\n<p>\u00a0<\/p>\n<h3>13. Gli studenti devono completare gli scenari del gioco di ruolo per completare il corso e ottenere il certificato di completamento?<\/h3>\n<p>A partire da oggi, gli studenti non devono completare gli scenari del gioco di ruolo per completare il corso o ricevere il certificato di completamento del corso. Il team sta monitorando l&#8217;efficacia di questa modalit\u00e0 di apprendimento e informer\u00e0 insegnanti (e studenti) in caso di cambiamenti futuri.<\/p>\n<h2 id=\"section-3\"><b>Gestione dei contenuti<\/b><\/h2>\n<h3><b>14. Poich\u00e9 gli insegnanti hanno ora accesso a Udemy Business, avranno anche accesso ai giochi di ruolo di altri insegnanti?<\/b><\/h3>\n<p>Udemy non consente ad altri insegnanti di accedere ai giochi di ruolo in altri corsi, ma li rende disponibili solo agli studenti iscritti al corso.<\/p>\n<p>\u00a0<\/p>\n<h3><b>15. Gli insegnanti potranno tenere una biblioteca dei giochi di ruolo e aggiungerli di conseguenza ai corsi?<\/b><\/h3>\n<p>Per il momento no. Questa funzionalit\u00e0 potrebbe far parte delle nostre future versioni, in quanto continuiamo a migliorare il gioco di ruolo per i nostri utenti.<\/p>\n<p>\u00a0<\/p>\n<h2 id=\"section-4\"><b>La tecnologia dietro Gioco di ruolo<\/b><\/h2>\n<h3><b>16. Udemy ha messo in piedi da sola le funzionalit\u00e0 principali di questo prodotto? O c&#8217;\u00e8 dietro ChatGPT?<\/b><\/h3>\n<p>Utilizziamo i modelli di OpenAI attraverso le loro API, ma si tratta di una combinazione di modelli diversi con impostazioni e modalit\u00e0 diverse.<\/p>\n<p>\u00a0<\/p>\n<h3><b>17. Quali sono le linee guida di sicurezza?<\/b><\/h3>\n<p>Ci affidiamo alle linee guida di protezione implicite fornite dal modello LLM stesso. L&#8217;attuale fornitore di LLM, OpenAI, ha implementato <a href=\"https:\/\/openai.com\/safety\/\">meccanismi di sicurezza<\/a> volti a prevenire la generazione di contenuti dannosi e a garantire che i personaggi simulati rimangano coerenti con i ruoli previsti definiti nelle richieste di sistema preparate automaticamente dal nostro servizio. I test interni condotti su enunciati esemplificativi indicano che il modello aderisce in linea di massima a queste aspettative. Questi risultati sono in linea con la documentazione e le garanzie di OpenAI in materia di sicurezza e aderenza al ruolo.<\/p>\n<p>\u00a0<\/p>\n<h3><b>18. Un insegnante deve partecipare al Programma GenAI di Udemy per creare scenari di gioco di ruolo per i corsi?<\/b><\/h3>\n<p>S\u00ec, gli insegnanti devono partecipare al Programma GenAI di Udemy per poter creare giochi di ruolo nei loro corsi. Gli insegnanti hanno una finestra di partecipazione annuale per decidere se partecipare o meno al Programma GenAI. Per ulteriori informazioni, consultare il sito Udemy <a href=\"https:\/\/support.udemy.com\/hc\/articles\/25180159300631-Instructor-Generative-AI-Policy?\">Politica sulla GenAI<\/a>.<\/p>\n<p>\u00a0<\/p>\n<h2 id=\"section-5\"><b>Monetizzazione<\/b><\/h2>\n<h3><b>19. Come verr\u00e0 calcolato il consumo dello studente? <\/b><\/h3>\n<p>Attualmente il consumo per i giochi di ruolo si basa su quanto tempo gli studenti si impegnano attivamente nell&#8217;attivit\u00e0. Ecco come funziona:<\/p>\n<ol>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Durata: il consumo dipende dalla durata del gioco di ruolo, in quanto il tempo di partecipazione attiva viene monitorato.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Monitoraggio accurato: un algoritmo basato sulla sessione assicura che venga conteggiato solo il coinvolgimento attivo. L&#8217;inattivit\u00e0 o l&#8217;abbandono della sessione interrompe il timer dopo un periodo definito.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Modello di pagamento: il tempo di consumo viene registrato e conteggiato nei pagamenti, in modo simile ai quiz o ai test pratici.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400\">In questo modo si garantisce un compenso equo basato sulla reale partecipazione e sull&#8217;impegno degli studenti.<\/span><\/p>\n<ol><!-- Content --><\/ol>\n<p>Questo modello potrebbe subire dei cambiamenti in futuro.<\/p>\n<h3><b>20. In che modo gli insegnanti otterranno entrate da Udemy Business associate ai giochi di ruolo?<\/b><\/h3>\n<p>Gli insegnanti guadagnano dai giochi di ruolo aziendali di Udemy in base a quanto segue:<\/p>\n<ol>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Guadagni basati sul consumo: i ricavi sono legati ai minuti totali che gli studenti trascorrono impegnandosi attivamente nei giochi di ruolo. In modo simile al compenso per i test pratici, gli esercizi di codifica e i quiz.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Monitoraggio separato: i minuti di consumo dei giochi di ruolo sono tracciati in modo indipendente ma combinati con altri contenuti del corso per la rendicontazione delle entrate.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Conteggio equo dell&#8217;impegno: viene conteggiata solo la partecipazione attiva, con meccanismi che evitino di gonfiare il tempo (ad esempio, limiti per l&#8217;inattivit\u00e0).<\/span><\/li>\n<\/ol>\n<p>\u00a0<\/p>\n<p><span style=\"font-weight: 400\">Questo sistema garantisce che gli istruttori siano compensati in modo equo per il tempo che gli studenti dedicano ai loro giochi di ruolo. I futuri aggiustamenti potrebbero incentivare ulteriormente la partecipazione.<\/span><\/p>\n<ol><!-- Content --><\/ol>\n<p>\u00a0<\/p>\n<p>Feedback? Condividi il tuo feedback o come utilizzi la funzione Gioco di ruolo nei tuoi corsi con altri insegnanti nella nostra <a href=\"https:\/\/community.udemy.com\/discussion\/160034\/megathread-say-hello-to-role-play\/p1?new=1\">community degli insegnanti<\/a>.  Non hai un account? Registrarsi \u00e8 facile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Feedback? Condividi il tuo feedback o come utilizzi la funzione Gioco di ruolo nei tuoi corsi con altri insegnanti nella nostra community degli insegnanti. Non hai un account? Registrarsi \u00e8 facile. \u00a0 Creare giochi di ruolo Aggiungere Gioco di ruolo ai tuoi corsi Gestione dei contenuti La tecnologia dietro Gioco di ruolo Monetizzazione \u00a0 Creare [&hellip;]<\/p>\n","protected":false},"author":124,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-36548","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/teach.udemy.com\/it\/wp-json\/wp\/v2\/pages\/36548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teach.udemy.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/teach.udemy.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/teach.udemy.com\/it\/wp-json\/wp\/v2\/users\/124"}],"replies":[{"embeddable":true,"href":"https:\/\/teach.udemy.com\/it\/wp-json\/wp\/v2\/comments?post=36548"}],"version-history":[{"count":3,"href":"https:\/\/teach.udemy.com\/it\/wp-json\/wp\/v2\/pages\/36548\/revisions"}],"predecessor-version":[{"id":36809,"href":"https:\/\/teach.udemy.com\/it\/wp-json\/wp\/v2\/pages\/36548\/revisions\/36809"}],"wp:attachment":[{"href":"https:\/\/teach.udemy.com\/it\/wp-json\/wp\/v2\/media?parent=36548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}